{"id":8603,"date":"2016-08-24T14:09:19","date_gmt":"2016-08-24T12:09:19","guid":{"rendered":"http:\/\/www.devuego.es\/blog\/?p=8603"},"modified":"2016-08-24T14:10:19","modified_gmt":"2016-08-24T12:10:19","slug":"segundo-trailer-zenith-aventureros","status":"publish","type":"post","link":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/","title":{"rendered":"Segundo trailer de Zenith: Aventureros"},"content":{"rendered":"<blockquote><p>En colaboraci\u00f3n con la editora <a href=\"https:\/\/www.devuego.es\/blog\/tag\/badland-indie\">BadLand Indie<\/a>, el estudio <a href=\"https:\/\/www.devuego.es\/blog\/tag\/infinigon-games\">Infinigon Games<\/a>, afincado en Barcelona, se encuentra desarrollado <strong>Zenith, un videojuego que pretende traernos las sensaciones de la era dorada de los RPG de acci\u00f3n pero ali\u00f1adas con una buena dosis de humor y parodia<\/strong>.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>En colaboraci\u00f3n con la editora BadLand Indie, el estudio Infinigon Games, afincado en Barcelona, se encuentra desarrollado Zenith, un videojuego<\/p>\n","protected":false},"author":1,"featured_media":7208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"colormag_page_layout":"default_layout","limit_modified_date":"","last_modified_date":"","footnotes":"","_share_on_mastodon":"0"},"categories":[870],"tags":[1254,1255,1256,20,32,62,219,566,726,838],"class_list":["post-8603","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-videos","tag-zenith","tag-arpg","tag-infinigon-games","tag-steam-greenlight","tag-rpg","tag-pc","tag-xbox-one","tag-windows","tag-ps4","tag-badland-indie","post_format-post-format-video"],"share_on_mastodon":{"url":"","error":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segundo trailer de Zenith: Aventureros | DeVuego Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Segundo trailer de Zenith: Aventureros | DeVuego Blog\" \/>\n<meta name=\"twitter:description\" content=\"En colaboraci\u00f3n con la editora BadLand Indie, el estudio Infinigon Games, afincado en Barcelona, se encuentra desarrollado Zenith, un videojuego\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/yovantichrist\" \/>\n<meta name=\"twitter:site\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yova Turnes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/\"},\"author\":{\"name\":\"Yova Turnes\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/19f1cceff613f8023f5f0f67e8da8b0c\"},\"headline\":\"Segundo trailer de Zenith: Aventureros\",\"datePublished\":\"2016-08-24T12:09:19+00:00\",\"dateModified\":\"2016-08-24T12:10:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/\"},\"wordCount\":52,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ZenithTitleScreen.jpg\",\"keywords\":[\"Zenith\",\"ARPG\",\"Infinigon Games\",\"Steam Greenlight\",\"RPG\",\"PC\",\"Xbox One\",\"Windows\",\"PS4\",\"Badland Indie\"],\"articleSection\":[\"V\u00eddeos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/\",\"name\":\"Segundo trailer de Zenith: Aventureros | DeVuego Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ZenithTitleScreen.jpg\",\"datePublished\":\"2016-08-24T12:09:19+00:00\",\"dateModified\":\"2016-08-24T12:10:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ZenithTitleScreen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/ZenithTitleScreen.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2016\\\/08\\\/24\\\/segundo-trailer-zenith-aventureros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segundo trailer de Zenith: Aventureros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"name\":\"DeVuego Blog\",\"description\":\"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"alternateName\":\"DeVuego Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\",\"name\":\"DeVuego\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"width\":1500,\"height\":399,\"caption\":\"DeVuego\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeVuego\",\"https:\\\/\\\/x.com\\\/DeVuego\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/devuego\",\"https:\\\/\\\/www.pinterest.com\\\/devuego\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/devuego.es\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/19f1cceff613f8023f5f0f67e8da8b0c\",\"name\":\"Yova Turnes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"caption\":\"Yova Turnes\"},\"description\":\"Padre | Inform\u00e1tico | Jugador | Metalero Comunicador, investigador y documentalista de videojuegos espa\u00f1oles Creador de DeVuego y DoblajeVideojuegos, entre otras.\",\"sameAs\":[\"http:\\\/\\\/www.linkedin.com\\\/in\\\/yovaturnes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/yovantichrist\"],\"url\":\"#molongui-disabled-link\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segundo trailer de Zenith: Aventureros | DeVuego Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/","twitter_card":"summary_large_image","twitter_title":"Segundo trailer de Zenith: Aventureros | DeVuego Blog","twitter_description":"En colaboraci\u00f3n con la editora BadLand Indie, el estudio Infinigon Games, afincado en Barcelona, se encuentra desarrollado Zenith, un videojuego","twitter_image":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg","twitter_creator":"@https:\/\/x.com\/yovantichrist","twitter_site":"@DeVuego","twitter_misc":{"Escrito por":"Yova Turnes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#article","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/"},"author":{"name":"Yova Turnes","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/19f1cceff613f8023f5f0f67e8da8b0c"},"headline":"Segundo trailer de Zenith: Aventureros","datePublished":"2016-08-24T12:09:19+00:00","dateModified":"2016-08-24T12:10:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/"},"wordCount":52,"commentCount":0,"publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg","keywords":["Zenith","ARPG","Infinigon Games","Steam Greenlight","RPG","PC","Xbox One","Windows","PS4","Badland Indie"],"articleSection":["V\u00eddeos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/","url":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/","name":"Segundo trailer de Zenith: Aventureros | DeVuego Blog","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#primaryimage"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg","datePublished":"2016-08-24T12:09:19+00:00","dateModified":"2016-08-24T12:10:19+00:00","breadcrumb":{"@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#primaryimage","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2016\/01\/ZenithTitleScreen.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.devuego.es\/blog\/2016\/08\/24\/segundo-trailer-zenith-aventureros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.devuego.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Segundo trailer de Zenith: Aventureros"}]},{"@type":"WebSite","@id":"https:\/\/www.devuego.es\/blog\/#website","url":"https:\/\/www.devuego.es\/blog\/","name":"DeVuego Blog","description":"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.","publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"alternateName":"DeVuego Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devuego.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.devuego.es\/blog\/#organization","name":"DeVuego","url":"https:\/\/www.devuego.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","width":1500,"height":399,"caption":"DeVuego"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeVuego","https:\/\/x.com\/DeVuego","https:\/\/es.linkedin.com\/company\/devuego","https:\/\/www.pinterest.com\/devuego\/","https:\/\/bsky.app\/profile\/devuego.es"]},{"@type":"Person","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/19f1cceff613f8023f5f0f67e8da8b0c","name":"Yova Turnes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","caption":"Yova Turnes"},"description":"Padre | Inform\u00e1tico | Jugador | Metalero Comunicador, investigador y documentalista de videojuegos espa\u00f1oles Creador de DeVuego y DoblajeVideojuegos, entre otras.","sameAs":["http:\/\/www.linkedin.com\/in\/yovaturnes\/","https:\/\/x.com\/https:\/\/x.com\/yovantichrist"],"url":"#molongui-disabled-link"}]}},"_links":{"self":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/8603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/comments?post=8603"}],"version-history":[{"count":0,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/8603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media\/7208"}],"wp:attachment":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media?parent=8603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/categories?post=8603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/tags?post=8603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}