{"id":4508,"date":"2015-02-24T10:42:48","date_gmt":"2015-02-24T09:42:48","guid":{"rendered":"http:\/\/www.devuego.es\/blog\/?p=4508"},"modified":"2015-04-16T18:54:19","modified_gmt":"2015-04-16T16:54:19","slug":"soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo","status":"publish","type":"post","link":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/","title":{"rendered":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo"},"content":{"rendered":"<p style=\"text-align: justify;\">Mientras algunos jugadores exigen experiencias cada vez m\u00e1s extensas y complejas, <strong>otros buscan experiencias\u00a0directas, simples<\/strong>, que les permitan disfrutar de los videojuegos en <strong>peque\u00f1as pero intensas dosis<\/strong>. Para estos \u00faltimos ha sido concebido <em>Soccertron<\/em>, el primer juego comercial de <a href=\"https:\/\/www.devuego.es\/bd\/festudio\/erosa-games\" target=\"_blank\">Erosa Games<\/a>.<\/p>\n<p style=\"text-align: justify;\"><strong>Soccertron es la evoluci\u00f3n de <em>Only One Ball<\/em><\/strong>, un videojuego creado por David Erosa, el desarrollador detr\u00e1s de Erosa Games, para la game jam <em>Ludum Dare #28<\/em> (que todav\u00eda es posible jugar en este enlace). Este juego est\u00e1 fuertemente inspirado por <em>Kung-Foot<\/em>, un minijuego incluido en <em>Rayman Legends<\/em> que mantuvo a su creador enganchado desde el primer momento que lo jug\u00f3.\u00a0Tras ver que sus amigos se pasaban una tarde entera jugando a la versi\u00f3n inicial del juego en su consola OUYA, <strong>David decidi\u00f3 que deber\u00eda mejorar y aumentar el juego y sacarlo a la luz<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-4512\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336-1024x640.png\" alt=\"Soccertron\" width=\"1024\" height=\"640\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336-1024x640.png 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336-600x375.png 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336-770x481.png 770w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193336.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Soccertron es un juego cuyo t\u00edtulo no debe llevarnos a equivocaci\u00f3n. Si bien su aspecto de gr\u00e1ficos de ne\u00f3n s\u00ed nos recuerda a la est\u00e9tica de la pel\u00edcula\u00a0Tron,\u00a0no ser\u00e1\u00a0s\u00f3lo el f\u00fatbol el deporte\u00a0representado de una manera particular y futurista, sino <strong>tambi\u00e9n el baloncesto, el volleyball y otras variaciones\u00a0de lo m\u00e1s original<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Las acciones que podemos realizar en todos ellos son siempre las mismas: movernos, saltar y golpear la bola, pero en cada juego las usaremos de un modo distinto. Cabe destacar que es\u00a0<strong>totalmente compatible con gamepad.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Aunque concebido para jugar contra otra persona (incluso 2 contra 2)<\/strong>, donde sin duda el juego alcanza su m\u00e1ximo apogeo de competitividad y adicci\u00f3n, Soccertron cuenta con la posibilidad de que los m\u00e1s solitarios podamos jugar contra la m\u00e1quina. Y aunque no contar\u00e1 con juego online de salida, su desarrollador ya nos ha confirmado que est\u00e1 trabajando en ello y que probablemente esta funcionalidad ser\u00e1 a\u00f1adida mediante una actualizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511.png\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-4513\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511-1024x640.png\" alt=\"Soccertron\" width=\"1024\" height=\"640\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511-1024x640.png 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511-600x375.png 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511-770x481.png 770w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193511.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>La jugabilidad sencilla y directa de Soccertron<\/strong> le ha valido ya\u00a0que a estas alturas cuente con un importante curriculum. Ha sido aprobado para ser publicado en <a href=\"https:\/\/www.devuego.es\/blog\/tag\/steam\">Steam<\/a> gracias al apoyo de la comunidad <a href=\"https:\/\/www.devuego.es\/blog\/tag\/steam-greenlight\">Greenlight<\/a>, que le daba luz verde el pasado 14 de noviembre tras poco m\u00e1s de 1 mes de ser lanzado a la comunidad. Adem\u00e1s, por esas fechas era tambi\u00e9n aceptado por el programa <a href=\"https:\/\/www.devuego.es\/blog\/tag\/idxbox\">ID@XBOX<\/a>, por lo que ya sabemos que al menos contar\u00e1 con versiones para PC via Steam <strong>-donde saldr\u00e1 el pr\u00f3ximo 12 de marzo-<\/strong> y para consolas via <a href=\"https:\/\/www.devuego.es\/blog\/tag\/xbox-one\">Xbox One<\/a>, con fecha todav\u00eda sin anunciar.<\/p>\n<p style=\"text-align: justify;\">Nosotros ya lo hemos probado y, aunque se trataba de una versi\u00f3n previa y no queremos adelantar nada del an\u00e1lisis que haremos en su momento, <strong>podemos asegurar que va a sorprender gratamente por su diversi\u00f3n y adicci\u00f3n.<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">\n<h4><a href=\"http:\/\/store.steampowered.com\/app\/334620\" target=\"_blank\">Soccertron en Steam<\/a><\/h4>\n<\/li>\n<li style=\"text-align: justify;\">\n<h4><a href=\"http:\/\/www.soccertrongame.com\/demo\/\" target=\"_blank\">Probar la demo en el navegador<\/a><\/h4>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Mientras algunos jugadores exigen experiencias cada vez m\u00e1s extensas y complejas, otros buscan experiencias\u00a0directas, simples, que les permitan disfrutar de<\/p>\n","protected":false},"author":1,"featured_media":4511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_layout":"default_layout","limit_modified_date":"","last_modified_date":"","footnotes":"","_share_on_mastodon":"0"},"categories":[664,864],"tags":[219,842,843,20,47,90,217],"class_list":["post-4508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juegos","category-op","tag-xbox-one","tag-soccertron","tag-erosa-games","tag-steam-greenlight","tag-steam","tag-arcade","tag-idxbox"],"share_on_mastodon":{"url":"","error":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog<\/title>\n<meta name=\"description\" content=\"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog\" \/>\n<meta name=\"twitter:description\" content=\"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/yovantichrist\" \/>\n<meta name=\"twitter:site\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yova Turnes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/\"},\"author\":{\"name\":\"Yova Turnes\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/19f1cceff613f8023f5f0f67e8da8b0c\"},\"headline\":\"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo\",\"datePublished\":\"2015-02-24T09:42:48+00:00\",\"dateModified\":\"2015-04-16T16:54:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/\"},\"wordCount\":486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/NeonSoccer_screenshot_20140612_193304.png\",\"keywords\":[\"Xbox One\",\"Soccertron\",\"Erosa Games\",\"Steam Greenlight\",\"Steam\",\"Arcade\",\"ID@Xbox\"],\"articleSection\":[\"Juegos\",\"OP\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/\",\"name\":\"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/NeonSoccer_screenshot_20140612_193304.png\",\"datePublished\":\"2015-02-24T09:42:48+00:00\",\"dateModified\":\"2015-04-16T16:54:19+00:00\",\"description\":\"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/NeonSoccer_screenshot_20140612_193304.png\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/NeonSoccer_screenshot_20140612_193304.png\",\"width\":3158,\"height\":1974},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2015\\\/02\\\/24\\\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"name\":\"DeVuego Blog\",\"description\":\"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"alternateName\":\"DeVuego Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\",\"name\":\"DeVuego\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"width\":1500,\"height\":399,\"caption\":\"DeVuego\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeVuego\",\"https:\\\/\\\/x.com\\\/DeVuego\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/devuego\",\"https:\\\/\\\/www.pinterest.com\\\/devuego\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/devuego.es\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/19f1cceff613f8023f5f0f67e8da8b0c\",\"name\":\"Yova Turnes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/b3ItFMpa_400x400.jpg\",\"caption\":\"Yova Turnes\"},\"description\":\"Padre | Inform\u00e1tico | Jugador | Metalero Comunicador, investigador y documentalista de videojuegos espa\u00f1oles Creador de DeVuego y DoblajeVideojuegos, entre otras.\",\"sameAs\":[\"http:\\\/\\\/www.linkedin.com\\\/in\\\/yovaturnes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/x.com\\\/yovantichrist\"],\"url\":\"#molongui-disabled-link\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog","description":"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/","twitter_card":"summary_large_image","twitter_title":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog","twitter_description":"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes","twitter_image":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png","twitter_creator":"@https:\/\/x.com\/yovantichrist","twitter_site":"@DeVuego","twitter_misc":{"Escrito por":"Yova Turnes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#article","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/"},"author":{"name":"Yova Turnes","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/19f1cceff613f8023f5f0f67e8da8b0c"},"headline":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo","datePublished":"2015-02-24T09:42:48+00:00","dateModified":"2015-04-16T16:54:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/"},"wordCount":486,"commentCount":0,"publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png","keywords":["Xbox One","Soccertron","Erosa Games","Steam Greenlight","Steam","Arcade","ID@Xbox"],"articleSection":["Juegos","OP"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/","url":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/","name":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo | DeVuego Blog","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#primaryimage"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png","datePublished":"2015-02-24T09:42:48+00:00","dateModified":"2015-04-16T16:54:19+00:00","description":"Soccertron, un arcade que mezcla deporte y neones para satisfacer a los jugadores \u00e1vidos de experiencias sencillas, directas y adictivas como las de antes","breadcrumb":{"@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#primaryimage","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2015\/02\/NeonSoccer_screenshot_20140612_193304.png","width":3158,"height":1974},{"@type":"BreadcrumbList","@id":"https:\/\/www.devuego.es\/blog\/2015\/02\/24\/soccertron-un-adictivo-arcade-de-neon-que-saldra-en-marzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.devuego.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Soccertron, un adictivo arcade de deporte y ne\u00f3n que saldr\u00e1 en marzo"}]},{"@type":"WebSite","@id":"https:\/\/www.devuego.es\/blog\/#website","url":"https:\/\/www.devuego.es\/blog\/","name":"DeVuego Blog","description":"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.","publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"alternateName":"DeVuego Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devuego.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.devuego.es\/blog\/#organization","name":"DeVuego","url":"https:\/\/www.devuego.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","width":1500,"height":399,"caption":"DeVuego"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeVuego","https:\/\/x.com\/DeVuego","https:\/\/es.linkedin.com\/company\/devuego","https:\/\/www.pinterest.com\/devuego\/","https:\/\/bsky.app\/profile\/devuego.es"]},{"@type":"Person","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/19f1cceff613f8023f5f0f67e8da8b0c","name":"Yova Turnes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2025\/03\/b3ItFMpa_400x400.jpg","caption":"Yova Turnes"},"description":"Padre | Inform\u00e1tico | Jugador | Metalero Comunicador, investigador y documentalista de videojuegos espa\u00f1oles Creador de DeVuego y DoblajeVideojuegos, entre otras.","sameAs":["http:\/\/www.linkedin.com\/in\/yovaturnes\/","https:\/\/x.com\/https:\/\/x.com\/yovantichrist"],"url":"#molongui-disabled-link"}]}},"_links":{"self":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/4508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/comments?post=4508"}],"version-history":[{"count":0,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/4508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media\/4511"}],"wp:attachment":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media?parent=4508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/categories?post=4508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/tags?post=4508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}