{"id":21736,"date":"2021-03-09T20:00:00","date_gmt":"2021-03-09T19:00:00","guid":{"rendered":"https:\/\/www.devuego.es\/blog\/?p=21736"},"modified":"2021-03-09T19:15:45","modified_gmt":"2021-03-09T18:15:45","slug":"magic-twins-devuego","status":"publish","type":"post","link":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/","title":{"rendered":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Magic Twins pondr\u00e1 a prueba nuestros reflejos y \u00bfnuestras amistades?<\/h2>\n\n\n\n<p>No os alarm\u00e9is que, aunque el mensaje sea un poco duro, no perder\u00e9is vuestras amistades por jugar a <strong>Magic Twins<\/strong>. Eso si, el nuevo juego de<a href=\"https:\/\/www.devuego.es\/bd\/festudio\/flying-beast-labs\"> Flying Beast Labs<\/a> pondr\u00e1 a prueba nuestros reflejos y nuestra cooperaci\u00f3n con el compa\u00f1ero de batalla. El estudio ha anunciado por fin la fecha de salida y llegar\u00e1 el d\u00eda 18 de marzo a Steam y a Nintendo Switch. Aqu\u00ed pod\u00e9is ver el tr\u00e1iler:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Magic Twins | Release Game Trailer - Flying Beast Labs [March 18th]\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/rqpw0pORu9I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Magic Twins es un juego cooperativo para dos jugadores donde tomaremos el control de las brujas m\u00e1s monas del mundo: Abra y Cadabra. <strong>Tendr\u00e1n que intercambiar sus poderes crom\u00e1tico<\/strong>s para poder derrotar a las hordas elementales y evitar una cat\u00e1strofe mayor. Malas lenguas dicen que esta situaci\u00f3n la provocaron ellas pero seguro que fue sin querer&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins3-1024x576.jpg\" alt=\"\" class=\"wp-image-21738\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins3-1024x576.jpg 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins3-600x338.jpg 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins3-768x432.jpg 768w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>La comunicaci\u00f3n ser\u00e1 primordial para acabar con los enemigos cuanto antes.<\/figcaption><\/figure>\n\n\n\n<p>Nos encontraremos una mec\u00e1nica de juego aparentemente sencilla pero que adquirir\u00e1 mucha m\u00e1s profundidad seg\u00fan vayamos avanzando en los niveles de Magic Twins. Sin duda nos encontramos ante uno de los juegos m\u00e1s coloridos y divertidos que podr\u00eda llegar este mes de marzo, ofreci\u00e9ndonos partidas cooperativas muy intensas donde<strong> nuestra capacidad de reacci\u00f3n y nuestra comunicaci\u00f3n con el compa\u00f1ero\/a<\/strong> ser\u00e1 primordial para poder acabar con las malignas hordas. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins2-1024x576.jpg\" alt=\"\" class=\"wp-image-21739\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins2-1024x576.jpg 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins2-600x338.jpg 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins2-768x432.jpg 768w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Habr\u00e1 una gran cantidad de niveles repartidos por toda la isla de Mallorca.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Enlaces de inter\u00e9s:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Web: <a href=\"https:\/\/flyingbeastlabs.com\/en\/\">https:\/\/flyingbeastlabs.com\/en\/<\/a><\/strong><\/li><li><strong>Steam: <a href=\"https:\/\/store.steampowered.com\/app\/1270080\/Magic_Twins\/\">https:\/\/store.steampowered.com\/app\/1270080\/Magic_Twins\/<\/a><\/strong><\/li><li><strong>Twitter: <a href=\"https:\/\/twitter.com\/FlyingBeastLabs\">https:\/\/twitter.com\/FlyingBeastLabs<\/a><\/strong><\/li><\/ul>\n\n\n\n<p>*<em>A\u00fan no est\u00e1 disponible el enlace en la Nintendo Eshop<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.<\/p>\n","protected":false},"author":85,"featured_media":21740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_layout":"default_layout","limit_modified_date":"","last_modified_date":"","footnotes":"","_share_on_mastodon":"0"},"categories":[2],"tags":[47,72,1767,2651,2996],"class_list":["post-21736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-steam","tag-cooperativo","tag-nintendo-switch","tag-magic-twins","tag-flying-beast-labs"],"share_on_mastodon":{"url":"","error":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?<\/title>\n<meta name=\"description\" content=\"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?\" \/>\n<meta name=\"twitter:description\" content=\"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@JlcLarrea\" \/>\n<meta name=\"twitter:site\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier Larrea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/\"},\"author\":{\"name\":\"Javier Larrea\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/b659f6f3f850dbd7f3944d8f6b8348f0\"},\"headline\":\"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?\",\"datePublished\":\"2021-03-09T19:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/\"},\"wordCount\":301,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/magic-twins.jpg\",\"keywords\":[\"Steam\",\"cooperativo\",\"Nintendo Switch\",\"Magic Twins\",\"flying Beast Labs\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/\",\"name\":\"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/magic-twins.jpg\",\"datePublished\":\"2021-03-09T19:00:00+00:00\",\"description\":\"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/magic-twins.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/magic-twins.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/03\\\/09\\\/magic-twins-devuego\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"name\":\"DeVuego Blog\",\"description\":\"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"alternateName\":\"DeVuego Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\",\"name\":\"DeVuego\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"width\":1500,\"height\":399,\"caption\":\"DeVuego\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeVuego\",\"https:\\\/\\\/x.com\\\/DeVuego\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/devuego\",\"https:\\\/\\\/www.pinterest.com\\\/devuego\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/devuego.es\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/b659f6f3f850dbd7f3944d8f6b8348f0\",\"name\":\"Javier Larrea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ESCb6ONXkAIKolj.jpg\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ESCb6ONXkAIKolj.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/ESCb6ONXkAIKolj.jpg\",\"caption\":\"Javier Larrea\"},\"description\":\"Hermano menor. Padre orgulloso de que su peque\u00f1a adore tambi\u00e9n los videojuegos tanto como yo. Cuando me dejan y la vida me lo permite escribo sobre videojuegos en DeVuego y anteriormente en Comunidad Xbox.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/JlcLarrea\"],\"url\":\"#molongui-disabled-link\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?","description":"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/","twitter_card":"summary_large_image","twitter_title":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?","twitter_description":"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.","twitter_image":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg","twitter_creator":"@JlcLarrea","twitter_site":"@DeVuego","twitter_misc":{"Escrito por":"Javier Larrea","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#article","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/"},"author":{"name":"Javier Larrea","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/b659f6f3f850dbd7f3944d8f6b8348f0"},"headline":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?","datePublished":"2021-03-09T19:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/"},"wordCount":301,"commentCount":0,"publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg","keywords":["Steam","cooperativo","Nintendo Switch","Magic Twins","flying Beast Labs"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/","url":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/","name":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#primaryimage"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg","datePublished":"2021-03-09T19:00:00+00:00","description":"Magic Twins nos pondr\u00e1 en el papel de las brujas Ada y Cadabra que tendr\u00e1n que cooperar para intentar evitar el COLORMAGEDDON.","breadcrumb":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#primaryimage","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/03\/magic-twins.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.devuego.es\/blog\/2021\/03\/09\/magic-twins-devuego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.devuego.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Magic Twins llegar\u00e1 este mismo mes. \u00bfPreparados para cooperar?"}]},{"@type":"WebSite","@id":"https:\/\/www.devuego.es\/blog\/#website","url":"https:\/\/www.devuego.es\/blog\/","name":"DeVuego Blog","description":"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.","publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"alternateName":"DeVuego Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devuego.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.devuego.es\/blog\/#organization","name":"DeVuego","url":"https:\/\/www.devuego.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","width":1500,"height":399,"caption":"DeVuego"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeVuego","https:\/\/x.com\/DeVuego","https:\/\/es.linkedin.com\/company\/devuego","https:\/\/www.pinterest.com\/devuego\/","https:\/\/bsky.app\/profile\/devuego.es"]},{"@type":"Person","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/b659f6f3f850dbd7f3944d8f6b8348f0","name":"Javier Larrea","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2020\/05\/ESCb6ONXkAIKolj.jpg","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2020\/05\/ESCb6ONXkAIKolj.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2020\/05\/ESCb6ONXkAIKolj.jpg","caption":"Javier Larrea"},"description":"Hermano menor. Padre orgulloso de que su peque\u00f1a adore tambi\u00e9n los videojuegos tanto como yo. Cuando me dejan y la vida me lo permite escribo sobre videojuegos en DeVuego y anteriormente en Comunidad Xbox.","sameAs":["https:\/\/x.com\/JlcLarrea"],"url":"#molongui-disabled-link"}]}},"_links":{"self":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/21736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/comments?post=21736"}],"version-history":[{"count":0,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/21736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media\/21740"}],"wp:attachment":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media?parent=21736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/categories?post=21736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/tags?post=21736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}