{"id":21181,"date":"2021-02-08T10:00:00","date_gmt":"2021-02-08T09:00:00","guid":{"rendered":"https:\/\/www.devuego.es\/blog\/?p=21181"},"modified":"2021-02-07T13:18:43","modified_gmt":"2021-02-07T12:18:43","slug":"mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero","status":"publish","type":"post","link":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/","title":{"rendered":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero"},"content":{"rendered":"\n<p><strong>Mutropolis<\/strong> es un proyecto que <strong><a href=\"https:\/\/www.devuego.es\/blog\/2016\/02\/15\/mutropolis-de-piritastudios-se-presenta-a-greenlight\/\">ve la luz tras 5 a\u00f1os de trabajo<\/a> de Pirita Studio<\/strong>. Una aventura <strong>dibujada a mano<\/strong> que, ambientada en el a\u00f1o 5000, nos transporta a un yacimiento arqueol\u00f3gico en el abandonado planeta Tierra.<\/p>\n\n\n\n<p>Este t\u00edtulo nos pone en la piel de Henry Dijon y su equipo para <strong>investigar a sus lejanos ancestros<\/strong>. En esta investigaci\u00f3n <strong>dar\u00e1n con la perdida Mutropolis, que alberga unas fuerzas oscuras que no deber\u00edan salir a la luz<\/strong>. Con esta premisa nos embarcamos en esta \u00e9pica sobre el descubrimiento, el pasado y los secretos de un  planeta abandonado. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/2-1024x576.jpg\" alt=\"\" class=\"wp-image-21246\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/2-1024x576.jpg 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/2-600x338.jpg 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/2-768x432.jpg 768w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/2.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Mutropolis es un <em><strong>point &amp; click<\/strong><\/em> hermoso, dibujado con cari\u00f1o y que<strong> llega este 18 de febrero a Windows, macOS y Linux<\/strong>. Beatriz Gasc\u00f3n y Juan Pablo Gonzalo nos traen esta aventura gr\u00e1fica en ingl\u00e9s y con gran variedad de subt\u00edtulos para que cualquiera pueda disfrutarlo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/9-1024x576.jpg\" alt=\"\" class=\"wp-image-21247\" srcset=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/9-1024x576.jpg 1024w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/9-600x338.jpg 600w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/9-768x432.jpg 768w, https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/9.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Puedes encontrarlo<a href=\"https:\/\/store.steampowered.com\/app\/1037120\/Mutropolis\/\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>en Steam a un precio de 19,99<\/strong><\/a> euros y con <strong>un 20% de descuento<\/strong> si lo reservas antes de la fecha de salida. Adem\u00e1s Pirita Studio cuenta con otros proyectos que puedes <strong><a href=\"https:\/\/www.piritastudio.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">visitar en su p\u00e1gina web<\/a><\/strong>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio. <\/p>\n","protected":false},"author":52,"featured_media":21245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_layout":"default_layout","limit_modified_date":"","last_modified_date":"","footnotes":"","_share_on_mastodon":"0"},"categories":[1760,2],"tags":[68,666,1298,1299],"class_list":["post-21181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lanzamientos","category-noticias","tag-indie","tag-madrid-games-week","tag-piritastudios","tag-mutropolis"],"share_on_mastodon":{"url":"","error":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog<\/title>\n<meta name=\"description\" content=\"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog\" \/>\n<meta name=\"twitter:description\" content=\"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:site\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nacho Ca\u00f1as\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/\"},\"author\":{\"name\":\"Nacho Ca\u00f1as\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/528ec9820818fc17a95341e5f6a3ded5\"},\"headline\":\"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero\",\"datePublished\":\"2021-02-08T09:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/\"},\"wordCount\":202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/0-cover-panoramic.jpg\",\"keywords\":[\"indie\",\"Madrid Games Week\",\"piritastudios\",\"mutropolis\"],\"articleSection\":[\"Lanzamientos\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/\",\"name\":\"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/0-cover-panoramic.jpg\",\"datePublished\":\"2021-02-08T09:00:00+00:00\",\"description\":\"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/0-cover-panoramic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/0-cover-panoramic.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2021\\\/02\\\/08\\\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"name\":\"DeVuego Blog\",\"description\":\"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"alternateName\":\"DeVuego Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\",\"name\":\"DeVuego\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"width\":1500,\"height\":399,\"caption\":\"DeVuego\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeVuego\",\"https:\\\/\\\/x.com\\\/DeVuego\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/devuego\",\"https:\\\/\\\/www.pinterest.com\\\/devuego\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/devuego.es\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/528ec9820818fc17a95341e5f6a3ded5\",\"name\":\"Nacho Ca\u00f1as\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g\",\"caption\":\"Nacho Ca\u00f1as\"},\"url\":\"#molongui-disabled-link\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog","description":"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/","twitter_card":"summary_large_image","twitter_title":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog","twitter_description":"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.","twitter_image":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg","twitter_creator":"@DeVuego","twitter_site":"@DeVuego","twitter_misc":{"Escrito por":"Nacho Ca\u00f1as","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#article","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/"},"author":{"name":"Nacho Ca\u00f1as","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/528ec9820818fc17a95341e5f6a3ded5"},"headline":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero","datePublished":"2021-02-08T09:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/"},"wordCount":202,"commentCount":0,"publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg","keywords":["indie","Madrid Games Week","piritastudios","mutropolis"],"articleSection":["Lanzamientos","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/","url":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/","name":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero | DeVuego Blog","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#primaryimage"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg","datePublished":"2021-02-08T09:00:00+00:00","description":"Mutropolis es una aventura de ciencia ficci\u00f3n que llega muy pronto de la mano de Pirita Studio. Un dibujo hecho a mano y mucho misterio.","breadcrumb":{"@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#primaryimage","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2021\/02\/0-cover-panoramic.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.devuego.es\/blog\/2021\/02\/08\/mutropolis-una-preciosa-aventura-de-misterio-que-llega-el-18-de-febrero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.devuego.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Mutropolis. Una preciosa aventura de misterio que llega el 18 de febrero"}]},{"@type":"WebSite","@id":"https:\/\/www.devuego.es\/blog\/#website","url":"https:\/\/www.devuego.es\/blog\/","name":"DeVuego Blog","description":"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.","publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"alternateName":"DeVuego Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devuego.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.devuego.es\/blog\/#organization","name":"DeVuego","url":"https:\/\/www.devuego.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","width":1500,"height":399,"caption":"DeVuego"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeVuego","https:\/\/x.com\/DeVuego","https:\/\/es.linkedin.com\/company\/devuego","https:\/\/www.pinterest.com\/devuego\/","https:\/\/bsky.app\/profile\/devuego.es"]},{"@type":"Person","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/528ec9820818fc17a95341e5f6a3ded5","name":"Nacho Ca\u00f1as","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/880088c7eb3ca78c044772d3725a3be32ced84475341c6d48eb46706523b36d2?s=96&d=mm&r=g","caption":"Nacho Ca\u00f1as"},"url":"#molongui-disabled-link"}]}},"_links":{"self":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/21181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/comments?post=21181"}],"version-history":[{"count":0,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/21181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media\/21245"}],"wp:attachment":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media?parent=21181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/categories?post=21181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/tags?post=21181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}