{"id":13040,"date":"2019-02-19T11:21:13","date_gmt":"2019-02-19T10:21:13","guid":{"rendered":"https:\/\/www.devuego.es\/blog\/?p=13040"},"modified":"2019-02-19T11:21:17","modified_gmt":"2019-02-19T10:21:17","slug":"nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril","status":"publish","type":"post","link":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/","title":{"rendered":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril"},"content":{"rendered":"\n<p style=\"text-align:center\"><em>\u201c<\/em>El t\u00edtulo&nbsp;del estudio malague\u00f1o&nbsp;iniciar\u00e1 una campa\u00f1a en Kickstarter en abril.<em>\u201d<\/em><\/p>\n\n\n\n<p>El estudio malague\u00f1o, <strong>Silent Road Games<\/strong>, presenta su nueva aventura espacial junto a <strong>Badland<\/strong>. Afterlight es el nombre del videojuego ambientado en la luna de Saturno, Titan. Silend Road Games buscar\u00e1 financiaci\u00f3n a trav\u00e9s de <em><strong>Kickstarter <\/strong><\/em><strong>a partir de abril<\/strong>, con vistas de tenerlo listo para el <strong>tercer cuarto de 2020. <\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cGracias\na <\/em>Badland<em>,\nhemos profesionalizado <\/em><em>Afterlight <\/em><em>en cuanto al desarrollo de negocio, marketing y\ngesti\u00f3n de recursos humanos\u201d<\/em><\/p><cite>Silent Road Games<\/cite><\/blockquote>\n\n\n\n<p><em>En Afterlight, encarnamos a Xin, <\/em>una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas. Para ello buscar\u00e1 la asistencia de su dron C.O.G., que la ayudar\u00e1 a resolver dif\u00edciles situaciones. Situado en el siglo XXII, Afterlight plantea una aventura ambiental de acci\u00f3n y puzles.<\/p>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/watch?v=KyKe4wafzNs&#038;feature=youtu.be&#038;utm_source=Nacional_BBDD+Multiplataforma&#038;utm_campaign=926aabe097-Nightmare+Boy_Fisico+Switch_COPY_01&#038;utm_medium=email&#038;utm_term=0_e486e701ce-926aabe097-249887281\n<\/div><figcaption>Trailer Oficial de Afterlight<\/figcaption><\/figure>\n\n\n\n<p>Su <strong>principal plataforma es PC<\/strong>, aunque no descartan el desarrollo para consolas. Con referencias como <strong>Journey, Inside, o el cine de Tarkovski<\/strong>, la aventura plantea una historia introspectiva en busca de la superaci\u00f3n a trav\u00e9s de la confianza. <em>\u201cBuscamos una jugabilidad precisa y \u00e1gil\u201d<\/em>, aclaran desde M\u00e1laga. <em>\u201cQueremos poner al jugador ante puzles \u00fanicos y ambientes de belleza extraterrestre, mientras descubre c\u00f3mo sobrevivir tras el fallo de la misi\u00f3n de la que nuestra protagonista es la \u00fanica superviviente\u201d<\/em>.<\/p>\n\n\n\n<p>Actualmente, <em>Silent Road Games forma parte del programa de aceleraci\u00f3n de Badland Publishing en M\u00e1laga<\/em>. Detallan adem\u00e1s que \u201cdebido al nivel tan temprano de desarrollo en que nos encontramos, es dif\u00edcil validar nuestra propuesta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.<\/p>\n","protected":false},"author":46,"featured_media":13042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_layout":"default_layout","limit_modified_date":"","last_modified_date":"","footnotes":"","_share_on_mastodon":"0"},"categories":[2],"tags":[62,68,174],"class_list":["post-13040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-pc","tag-indie","tag-kickstarter"],"share_on_mastodon":{"url":"","error":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog<\/title>\n<meta name=\"description\" content=\"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog\" \/>\n<meta name=\"twitter:description\" content=\"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:site\" content=\"@DeVuego\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel S. Lemos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/\"},\"author\":{\"name\":\"Manuel S. Lemos\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/1153f45dcb39a093289142f45152cf10\"},\"headline\":\"Nuevo teaser de Afterlight y futuro Kickstarter en Abril\",\"datePublished\":\"2019-02-19T10:21:13+00:00\",\"dateModified\":\"2019-02-19T10:21:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/\"},\"wordCount\":327,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/unnamed1.jpg\",\"keywords\":[\"PC\",\"indie\",\"Kickstarter\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/\",\"name\":\"Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/unnamed1.jpg\",\"datePublished\":\"2019-02-19T10:21:13+00:00\",\"dateModified\":\"2019-02-19T10:21:17+00:00\",\"description\":\"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/unnamed1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/unnamed1.jpg\",\"width\":1200,\"height\":693,\"caption\":\"Afterlight\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/2019\\\/02\\\/19\\\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nuevo teaser de Afterlight y futuro Kickstarter en Abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"name\":\"DeVuego Blog\",\"description\":\"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\"},\"alternateName\":\"DeVuego Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#organization\",\"name\":\"DeVuego\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"contentUrl\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logodevuegoblogazulgrande.jpg\",\"width\":1500,\"height\":399,\"caption\":\"DeVuego\"},\"image\":{\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeVuego\",\"https:\\\/\\\/x.com\\\/DeVuego\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/devuego\",\"https:\\\/\\\/www.pinterest.com\\\/devuego\\\/\",\"https:\\\/\\\/bsky.app\\\/profile\\\/devuego.es\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.devuego.es\\\/blog\\\/#\\\/schema\\\/person\\\/1153f45dcb39a093289142f45152cf10\",\"name\":\"Manuel S. Lemos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g\",\"caption\":\"Manuel S. Lemos\"},\"url\":\"#molongui-disabled-link\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog","description":"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/","twitter_card":"summary_large_image","twitter_title":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog","twitter_description":"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.","twitter_image":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg","twitter_creator":"@DeVuego","twitter_site":"@DeVuego","twitter_misc":{"Escrito por":"Manuel S. Lemos","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#article","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/"},"author":{"name":"Manuel S. Lemos","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/1153f45dcb39a093289142f45152cf10"},"headline":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril","datePublished":"2019-02-19T10:21:13+00:00","dateModified":"2019-02-19T10:21:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/"},"wordCount":327,"commentCount":1,"publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg","keywords":["PC","indie","Kickstarter"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/","url":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/","name":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril | DeVuego Blog","isPartOf":{"@id":"https:\/\/www.devuego.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#primaryimage"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg","datePublished":"2019-02-19T10:21:13+00:00","dateModified":"2019-02-19T10:21:17+00:00","description":"En Afterlight encarnamos a Xin, una astronauta que, tras un accidente, debe sobrevivir no s\u00f3lo a las secuelas f\u00edsicas sino tambi\u00e9n a las psicol\u00f3gicas.","breadcrumb":{"@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#primaryimage","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2019\/02\/unnamed1.jpg","width":1200,"height":693,"caption":"Afterlight"},{"@type":"BreadcrumbList","@id":"https:\/\/www.devuego.es\/blog\/2019\/02\/19\/nuevo-teaser-de-afterlight-y-futuro-kickstarter-en-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.devuego.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Nuevo teaser de Afterlight y futuro Kickstarter en Abril"}]},{"@type":"WebSite","@id":"https:\/\/www.devuego.es\/blog\/#website","url":"https:\/\/www.devuego.es\/blog\/","name":"DeVuego Blog","description":"En el blog de DeVuego cubrimos todo aquello que sobre videojuegos se hace en Espa\u00f1a, con especial dedicaci\u00f3n a los videojuegos espa\u00f1oles y sus creadores.","publisher":{"@id":"https:\/\/www.devuego.es\/blog\/#organization"},"alternateName":"DeVuego Blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.devuego.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.devuego.es\/blog\/#organization","name":"DeVuego","url":"https:\/\/www.devuego.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","contentUrl":"https:\/\/www.devuego.es\/blog\/wp-content\/uploads\/2024\/11\/cropped-logodevuegoblogazulgrande.jpg","width":1500,"height":399,"caption":"DeVuego"},"image":{"@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeVuego","https:\/\/x.com\/DeVuego","https:\/\/es.linkedin.com\/company\/devuego","https:\/\/www.pinterest.com\/devuego\/","https:\/\/bsky.app\/profile\/devuego.es"]},{"@type":"Person","@id":"https:\/\/www.devuego.es\/blog\/#\/schema\/person\/1153f45dcb39a093289142f45152cf10","name":"Manuel S. Lemos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13729b66b533da3072f8b70d43d8b62a41aa0bfb85949a76cfdde23e5780b93d?s=96&d=mm&r=g","caption":"Manuel S. Lemos"},"url":"#molongui-disabled-link"}]}},"_links":{"self":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/13040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/comments?post=13040"}],"version-history":[{"count":0,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/posts\/13040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media\/13042"}],"wp:attachment":[{"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/media?parent=13040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/categories?post=13040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.devuego.es\/blog\/wp-json\/wp\/v2\/tags?post=13040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}